{"id":245,"count":2,"description":"","link":"https:\/\/www.embracinghome.blog\/index.php\/tag\/family\/","name":"family","slug":"family","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.embracinghome.blog\/index.php\/wp-json\/wp\/v2\/tags\/245","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.embracinghome.blog\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.embracinghome.blog\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.embracinghome.blog\/index.php\/wp-json\/wp\/v2\/posts?tags=245"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}